{"id":83,"date":"2022-10-17T11:39:28","date_gmt":"2022-10-17T11:39:28","guid":{"rendered":"https:\/\/sites.unimi.it\/pirolacarlo\/?page_id=83"},"modified":"2025-11-20T12:15:07","modified_gmt":"2025-11-20T11:15:07","slug":"dottorandi","status":"publish","type":"page","link":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/gruppo-di-ricerca\/dottorandi\/","title":{"rendered":"PhDs"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><a href=\"https:\/\/sites.unimi.it\/pirolacarlo\/en\/dottorandi\/alessio-ferlin\/\">Alessio Ferlin<\/a><\/h2>\n\n\n\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Ferlin-edited-1024x1024.jpeg\" alt=\"\" class=\"wp-image-1399 size-full\" srcset=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Ferlin-edited-1024x1024.jpeg 1024w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Ferlin-edited-300x300.jpeg 300w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Ferlin-edited-150x150.jpeg 150w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Ferlin-edited-768x769.jpeg 768w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Ferlin-edited-12x12.jpeg 12w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Ferlin-edited.jpeg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Dottorando in Chimica Industriale, con background in distillazione azeotropica, attualmente impegnato nello sviluppo di tecnologie innovative per la depolimerizzazione della poliammide 6 a caprolattame tramite pirolisi alcalina, in stretta collaborazione con il mondo industriale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/sites.unimi.it\/pirolacarlo\/en\/alessio-ferlin\/\">Leggi di pi\u00f9&#8230;<\/a><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-neve-link-color-color has-alpha-channel-opacity has-neve-link-color-background-color has-background\"\/>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/sites.unimi.it\/pirolacarlo\/en\/gruppo-di-ricerca\/dottorandi\/nicola-bernareggi\/\">Nicola Bernareggi<\/a><\/h2>\n\n\n\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-1024x1024.jpg\" alt=\"\" class=\"wp-image-1396 size-full\" srcset=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-1024x1024.jpg 1024w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-300x300.jpg 300w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-150x150.jpg 150w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-768x768.jpg 768w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-1536x1536.jpg 1536w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-2048x2048.jpg 2048w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2025\/11\/Bernareggi-edited-12x12.jpg 12w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Dottorando in Chimica Industriale laureato in Industrial Chemistry con una tesi sulla catalisi eterogenea in impianti in continuo.<br>Il progetto di dottorato, dal titolo &#8220;Production of adipic acid from renewable resource by heterogeneous catalysis&#8221; si focalizza sulla produzione di Acido Adipico a partire da materie prime di origine biologica, in particolare da derivati di lignina e cellulosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/sites.unimi.it\/pirolacarlo\/en\/gruppo-di-ricerca\/dottorandi\/nicola-bernareggi\/\">Leggi di pi\u00f9&#8230;<\/a><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-neve-link-color-color has-alpha-channel-opacity has-neve-link-color-background-color has-background\"\/>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-neve-link-hover-color-color has-text-color wp-block-heading\"><strong>Gi\u00e0 dottorati<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h4 class=\"wp-block-heading\"><a href=\"http:\/\/sites.unimi.it\/pirolacarlo\/en\/dottorandi\/arian-grainca\/\">Arian Grainca<\/a><\/h4>\n\n\n\n<div class=\"wp-block-group is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-fbe4aca3 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/arian-edited-1024x1024.jpeg\" alt=\"\" class=\"wp-image-903\" width=\"150\" height=\"150\" srcset=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/arian-edited-1024x1024.jpeg 1024w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/arian-edited-300x300.jpeg 300w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/arian-edited-150x150.jpeg 150w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/arian-edited-768x768.jpeg 768w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/arian-edited-12x12.jpeg 12w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/arian-edited.jpeg 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ex-Dottorando di ricerca presso il laboratorio impianti pilota sotto supervisione del Prof. Carlo Pirola.<br>La linea di ricerca principale seguiva l&#8217;idrogenazione della CO<sub>2<\/sub>\u00a0catalytical hydrogenation for the formation of hydrocarbons, the utilization of dynamic simulation softwares and studies of danger and operativity of laboratory plants.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/sites.unimi.it\/pirolacarlo\/en\/dottorandi\/giulia-tonsi\/\">Giulia Tonsi<\/a><\/h4>\n\n\n\n<div class=\"wp-block-group is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-fbe4aca3 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/giulia-1-edited-150x150.jpeg\" alt=\"\" class=\"wp-image-1159\" srcset=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/giulia-1-edited-150x150.jpeg 150w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/giulia-1-edited-300x300.jpeg 300w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/giulia-1-edited-1024x1024.jpeg 1024w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/giulia-1-edited-768x767.jpeg 768w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/giulia-1-edited-12x12.jpeg 12w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/giulia-1-edited.jpeg 1255w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ex-Dottoranda di ricerca presso il laboratorio impianti pilota sotto supervisione del Prof. Carlo Pirola, seguiva il progetto dal titolo: &#8220;Recovery And Separation Processes In The Recycling Chain Of Polyamide Plastic Materials To Obtain Eco-Sustainable Raw Materials&#8221; in collaborazione con Radici InNova Spa.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/sites.unimi.it\/pirolacarlo\/en\/dottorandi\/elisa-zanella\/\">Elisa Zanella<\/a><\/h4>\n\n\n\n<div class=\"wp-block-group is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-14d7fe8f wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/elisa_1-edited-150x150.jpeg\" alt=\"\" class=\"wp-image-921\" srcset=\"https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/elisa_1-edited-150x150.jpeg 150w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/elisa_1-edited-300x300.jpeg 300w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/elisa_1-edited-1024x1024.jpeg 1024w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/elisa_1-edited-768x768.jpeg 768w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/elisa_1-edited-12x12.jpeg 12w, https:\/\/sites.unimi.it\/pirolacarlo\/wp-content\/uploads\/2023\/03\/elisa_1-edited.jpeg 1536w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Ex-Dottoranda di ricerca presso il laboratorio impianti pilota sotto supervisione del Prof. Carlo Pirola.<br>Il progetto di dottorato dal titolo: \u201cInnovation and optimization of the hydrogen transport and distribution chain as a green and renewable energy vector\u201d, in collaborazione con Regas srl.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Alessio Ferlin Dottorando in Chimica Industriale, con background in distillazione azeotropica, attualmente impegnato nello sviluppo di tecnologie innovative per la depolimerizzazione della poliammide 6 a caprolattame tramite pirolisi alcalina, in stretta collaborazione con il mondo industriale. Leggi di pi\u00f9&#8230; Nicola Bernareggi Dottorando in Chimica Industriale laureato in Industrial Chemistry con una tesi sulla catalisi eterogenea&hellip;&nbsp;<a href=\"https:\/\/sites.unimi.it\/pirolacarlo\/en\/gruppo-di-ricerca\/dottorandi\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">PhDs<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":1142,"parent":320,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-83","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/pages\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":66,"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/pages\/83\/revisions"}],"predecessor-version":[{"id":1442,"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/pages\/83\/revisions\/1442"}],"up":[{"embeddable":true,"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/pages\/320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/media\/1142"}],"wp:attachment":[{"href":"https:\/\/sites.unimi.it\/pirolacarlo\/en\/wp-json\/wp\/v2\/media?parent=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}